{"id":39172,"date":"2026-09-02T15:26:38","date_gmt":"2026-09-02T14:26:38","guid":{"rendered":"https:\/\/digilicenses.com\/?post_type=private_sale&#038;p=39172"},"modified":"2026-09-02T15:32:22","modified_gmt":"2026-09-02T14:32:22","slug":"matthew","status":"publish","type":"private_sale","link":"https:\/\/digilicenses.com\/en\/private-sale\/matthew\/","title":{"rendered":"Matthew"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-39172","private_sale","type-private_sale","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matthew - digilicenses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digilicenses.com\/en\/private-sale\/matthew\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matthew - digilicenses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digilicenses.com\/en\/private-sale\/matthew\/\" \/>\n<meta property=\"og:site_name\" content=\"digilicenses\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T14:32:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digilicenses.com\\\/private-sale\\\/matthew\\\/\",\"url\":\"https:\\\/\\\/digilicenses.com\\\/private-sale\\\/matthew\\\/\",\"name\":\"Matthew - digilicenses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digilicenses.com\\\/#website\"},\"datePublished\":\"2026-09-02T14:26:38+00:00\",\"dateModified\":\"2026-09-02T14:32:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digilicenses.com\\\/private-sale\\\/matthew\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digilicenses.com\\\/private-sale\\\/matthew\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digilicenses.com\\\/private-sale\\\/matthew\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/digilicenses.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matthew\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digilicenses.com\\\/#website\",\"url\":\"https:\\\/\\\/digilicenses.com\\\/\",\"name\":\"digilicenses\",\"description\":\"Shop digilicenses\",\"publisher\":{\"@id\":\"https:\\\/\\\/digilicenses.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digilicenses.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/digilicenses.com\\\/#organization\",\"name\":\"digilicenses\",\"url\":\"https:\\\/\\\/digilicenses.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digilicenses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/digilicenses.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-Logotipo-1200x300-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/digilicenses.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-Logotipo-1200x300-1-1.jpg\",\"width\":1044,\"height\":300,\"caption\":\"digilicenses\"},\"image\":{\"@id\":\"https:\\\/\\\/digilicenses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matthew - digilicenses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digilicenses.com\/en\/private-sale\/matthew\/","og_locale":"en_US","og_type":"article","og_title":"Matthew - digilicenses","og_url":"https:\/\/digilicenses.com\/en\/private-sale\/matthew\/","og_site_name":"digilicenses","article_modified_time":"2026-09-02T14:32:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/digilicenses.com\/private-sale\/matthew\/","url":"https:\/\/digilicenses.com\/private-sale\/matthew\/","name":"Matthew - digilicenses","isPartOf":{"@id":"https:\/\/digilicenses.com\/#website"},"datePublished":"2026-09-02T14:26:38+00:00","dateModified":"2026-09-02T14:32:22+00:00","breadcrumb":{"@id":"https:\/\/digilicenses.com\/private-sale\/matthew\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digilicenses.com\/private-sale\/matthew\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/digilicenses.com\/private-sale\/matthew\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/digilicenses.com\/"},{"@type":"ListItem","position":2,"name":"Matthew"}]},{"@type":"WebSite","@id":"https:\/\/digilicenses.com\/#website","url":"https:\/\/digilicenses.com\/","name":"digital licenses","description":"Shop digilicenses","publisher":{"@id":"https:\/\/digilicenses.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digilicenses.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/digilicenses.com\/#organization","name":"digital licenses","url":"https:\/\/digilicenses.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digilicenses.com\/#\/schema\/logo\/image\/","url":"https:\/\/digilicenses.com\/wp-content\/uploads\/2022\/06\/cropped-Logotipo-1200x300-1-1.jpg","contentUrl":"https:\/\/digilicenses.com\/wp-content\/uploads\/2022\/06\/cropped-Logotipo-1200x300-1-1.jpg","width":1044,"height":300,"caption":"digilicenses"},"image":{"@id":"https:\/\/digilicenses.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/digilicenses.com\/en\/wp-json\/wp\/v2\/private_sale\/39172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digilicenses.com\/en\/wp-json\/wp\/v2\/private_sale"}],"about":[{"href":"https:\/\/digilicenses.com\/en\/wp-json\/wp\/v2\/types\/private_sale"}],"wp:attachment":[{"href":"https:\/\/digilicenses.com\/en\/wp-json\/wp\/v2\/media?parent=39172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}